{"id":6232,"date":"2021-11-15T09:13:56","date_gmt":"2021-11-15T08:13:56","guid":{"rendered":"https:\/\/www.chiefslife.com\/it-ch\/?p=6232"},"modified":"2022-03-15T11:57:57","modified_gmt":"2022-03-15T10:57:57","slug":"nutrizione-calorie","status":"publish","type":"post","link":"https:\/\/www.chiefslife.com\/it-ch\/nutrizione-calorie\/","title":{"rendered":"Nutrizione: Calorie"},"content":{"rendered":"\n<div class=\"wp-block-cover\"><img decoding=\"async\" class=\"wp-block-cover__image-background wp-image-6446\" alt=\"\" src=\"https:\/\/www.chiefslife.com\/fr-ch\/wp-content\/uploads\/sites\/7\/2021\/11\/Calories.jpg\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h1 class=\"has-text-align-left wp-block-heading\">Calorie<\/h1>\n\n\n\n<p>Esistono al riguardo teorie non proprio corrette \u2013 una di queste \u00e8: \u00abUna caloria corrisponde a una caloria\u00bb. Indipendentemente dal fatto che una caloria provenga da carboidrati, grassi o proteine, questa avrebbe lo stesso effetto sul peso corporeo. In tal senso, i carboidrati, i grassi e le proteine dovrebbero scatenare le stesse reazioni nel corpo \u2013 ma non \u00e8 cos\u00ec. Ad esempio, le proteine aumentano il consumo di calorie dopo un pasto in maniera pi\u00f9 marcata rispetto ai carboidrati e ai grassi.<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Calorie Esistono al riguardo teorie non proprio corrette \u2013 una di queste \u00e8: \u00abUna caloria corrisponde a una caloria\u00bb. Indipendentemente dal fatto che una caloria provenga da carboidrati, grassi o proteine, questa avrebbe lo stesso effetto sul peso corporeo. In tal senso, i carboidrati, i grassi e le proteine dovrebbero scatenare le stesse reazioni nel [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[103],"tags":[],"class_list":["post-6232","post","type-post","status-publish","format-standard","hentry","category-blog-texte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/posts\/6232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/comments?post=6232"}],"version-history":[{"count":0,"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/posts\/6232\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/media?parent=6232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/categories?post=6232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chiefslife.com\/it-ch\/wp-json\/wp\/v2\/tags?post=6232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}